{"id":2673,"date":"2025-01-27T09:41:12","date_gmt":"2025-01-27T08:41:12","guid":{"rendered":"https:\/\/semperaltius.nl\/?p=2673"},"modified":"2025-03-11T09:55:24","modified_gmt":"2025-03-11T08:55:24","slug":"7x7-25-januari-2025","status":"publish","type":"post","link":"https:\/\/semperaltius.nl\/index.php\/2025\/01\/27\/7x7-25-januari-2025\/","title":{"rendered":"7x7 - 25 januari 2025"},"content":{"rendered":"\n<p>Hans van den Berg heeft weer een mooi verslag geschreven.<br><br>Deze is te lezen op zijn <a href=\"https:\/\/hansjevandenberg.jouwweb.nl\/ut-menu\/voorwoord\/semper-altius\/seizoen2425\/25-januari\" data-type=\"link\" data-id=\"https:\/\/hansjevandenberg.jouwweb.nl\/ut-menu\/voorwoord\/semper-altius\/seizoen2425\/25-januari\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>website<\/strong><\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hans van den Berg heeft weer een mooi verslag geschreven. Deze is te lezen op zijn website!<\/p>\n","protected":false},"author":10,"featured_media":2674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74],"tags":[],"class_list":["post-2673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-verslagen-7x7"],"publishpress_future_action":{"enabled":false,"date":"2026-06-13 15:18:43","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/semperaltius.nl\/index.php\/wp-json\/wp\/v2\/posts\/2673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semperaltius.nl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semperaltius.nl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semperaltius.nl\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/semperaltius.nl\/index.php\/wp-json\/wp\/v2\/comments?post=2673"}],"version-history":[{"count":4,"href":"https:\/\/semperaltius.nl\/index.php\/wp-json\/wp\/v2\/posts\/2673\/revisions"}],"predecessor-version":[{"id":2818,"href":"https:\/\/semperaltius.nl\/index.php\/wp-json\/wp\/v2\/posts\/2673\/revisions\/2818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semperaltius.nl\/index.php\/wp-json\/wp\/v2\/media\/2674"}],"wp:attachment":[{"href":"https:\/\/semperaltius.nl\/index.php\/wp-json\/wp\/v2\/media?parent=2673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semperaltius.nl\/index.php\/wp-json\/wp\/v2\/categories?post=2673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semperaltius.nl\/index.php\/wp-json\/wp\/v2\/tags?post=2673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}